{"id":1358,"date":"2020-03-20T21:33:58","date_gmt":"2020-03-20T21:33:58","guid":{"rendered":"https:\/\/mgapress.com.br\/blog\/?p=1358"},"modified":"2020-06-23T18:46:29","modified_gmt":"2020-06-23T18:46:29","slug":"6-ferramentas-de-marketing-na-area-da-saude-em-2020","status":"publish","type":"post","link":"https:\/\/mgapress.com.br\/blog\/6-ferramentas-de-marketing-na-area-da-saude-em-2020\/","title":{"rendered":"6  Ferramentas de marketing na \u00e1rea da sa\u00fade em 2020"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 7 minutos<\/small><\/p> <p><span style=\"font-weight: 400;\">A transforma\u00e7\u00e3o digital \u00e9 um tema que vem sendo falado com bastante frequ\u00eancia no mundo atual, atravessando diversos setores econ\u00f4micos, sendo um deles a sa\u00fade. O marketing em servi\u00e7os de sa\u00fade \u00e9 um enorme desafio devido a sua complexidade, concorr\u00eancia acirrada e especificidades.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para superar essa barreira, o <\/span><a href=\"https:\/\/mgapress.com.br\/blog\/marketing-digital-x-tradicional-qual-e-melhor-para-o-seu-negocio\/\"><span style=\"font-weight: 400;\">marketing tradicional<\/span><\/a><span style=\"font-weight: 400;\"> por si s\u00f3 j\u00e1 n\u00e3o \u00e9 a melhor alternativa, \u00e9 preciso \u201cchamar refor\u00e7os\u201d no marketing digital e suas ferramentas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Foi pensando nisso que a MGA Press desenvolveu uma lista com as 5 principais tend\u00eancias no marketing de sa\u00fade para 2020.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entretanto, \u00e9 importante enfatizar que elas n\u00e3o est\u00e3o priorizadas por ordem ou sequ\u00eancia em que devem ser consideradas. Trata-se apenas de uma listagem dentre muitas outras pr\u00e1ticas apontadas por especialistas como inova\u00e7\u00f5es importantes para esse ano.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">As 6 ferramentas de marketing na sa\u00fade<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">As principais tend\u00eancias incluem <a href=\"https:\/\/crmpiperun.com\/blog\/o-que-e-crm\/\">CRM<\/a>, Big Data, Intelig\u00eancia Artificial e Machine Learning, Telemedicina e assistentes virtuais. Confira abaixo uma descri\u00e7\u00e3o detalhada de cada uma delas.\u00a0<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\">\n<h3><strong>CRM<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1363 size-full\" src=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/6242723181625344.jpeg\" alt=\"\" width=\"684\" height=\"457\" srcset=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/6242723181625344.jpeg 684w, https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/6242723181625344-300x200.jpeg 300w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Um dos mais importantes relacionamentos na sa\u00fade \u00e9 a rela\u00e7\u00e3o m\u00e9dico-paciente, onde o prestador de servi\u00e7o deve criar empatia com o paciente e entender bem as suas necessidades e n\u00e3o apenas fornecer informa\u00e7\u00f5es quanto aos sintomas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dentre os <\/span><a href=\"https:\/\/issuu.com\/rafaelataylor2\/docs\/marketing_de_relacionamento_-_itzha\"><span style=\"font-weight: 400;\">6 objetivos do marketing de relacionamento<\/span><\/a><span style=\"font-weight: 400;\">, base do CRM, est\u00e1 o papel do cliente individual no processo de co gera\u00e7\u00e3o de valor que ele tem com o prestador de servi\u00e7os. Ou seja, o cliente auxilia a empresa a fornecer o pacote de servi\u00e7os que ele acredita ser essencial.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isso apenas refor\u00e7a ainda mais o papel do CRM para personalizar a informa\u00e7\u00e3o ao cliente, com processos simplificados e eficazes para atender cada caso. Al\u00e9m do mais, h\u00e1 ainda a facilidade de acesso e mensura\u00e7\u00e3o de resultados de modo a melhorar continuamente esta rela\u00e7\u00e3o.<\/span><\/p>\n<p><strong>2.\u00a0<a href=\"http:\/\/www.mgapress.com.br\">Assessoria de imprensa<\/a><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1364 size-full aligncenter\" src=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/4623643051819008.jpeg\" alt=\"\" width=\"663\" height=\"436\" srcset=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/4623643051819008.jpeg 663w, https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/4623643051819008-300x197.jpeg 300w, https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/4623643051819008-350x230.jpeg 350w, https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/4623643051819008-380x249.jpeg 380w, https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/4623643051819008-650x427.jpeg 650w\" sizes=\"auto, (max-width: 663px) 100vw, 663px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">De todas as ferramentas de marketing em servi\u00e7os de sa\u00fade que est\u00e3o sendo apresentadas nesse texto e que j\u00e1 s\u00e3o utilizadas no mercado, a assessoria de imprensa pode at\u00e9 mesmo surpreender por estar nessa lista. Mas, a verdade \u00e9 que esse tipo de ferramenta \u00e9 e sempre vai ser atual.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Uma assessoria de imprensa de qualidade traz in\u00fameros benef\u00edcios para os neg\u00f3cios assim como aumento da notoriedade de marca, reconhecimento de marca, autoridade, engajamento e mais clientes.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00f3s mesmos, na MGA Press, temos diversos <\/span><a href=\"https:\/\/mgapress.com.br\/blog\/estudo-de-caso-assessoria-de-imprensa-para-saude\/\"><span style=\"font-weight: 400;\">casos de sucesso<\/span><\/a><span style=\"font-weight: 400;\"> na implementa\u00e7\u00e3o de assessoria de imprensa para sa\u00fade.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O Fleurity Coletor Menstrual, por exemplo, foi um dos clientes que aumentou sensivelmente a sua notoriedade atrav\u00e9s de uma ampla cobertura de m\u00eddia feita por nossos profissionais qualificados.<\/span><\/p>\n<p><strong>3.\u00a0\u00a0Big Data<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1365 size-full\" src=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/5122153060761600.jpeg\" alt=\"\" width=\"679\" height=\"505\" srcset=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/5122153060761600.jpeg 679w, https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/5122153060761600-300x223.jpeg 300w\" sizes=\"auto, (max-width: 679px) 100vw, 679px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Em tempos de grande <\/span><a href=\"https:\/\/mgapress.com.br\/blog\/saiba-qual-e-o-impacto-da-tecnologia-na-assessoria-de-imprensa\/\"><span style=\"font-weight: 400;\">evolu\u00e7\u00e3o tecnol\u00f3gica <\/span><\/a><span style=\"font-weight: 400;\">como esses em que estamos vivendo, o volume de dados e informa\u00e7\u00f5es armazenadas em nuvem cresce assustadoramente. Assim como os dados fornecidos e gerenciados por bancos de dados no mundo inteiro e a todo momento, \u00e9 de suma import\u00e2ncia filtrar e analisar bem essas informa\u00e7\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No marketing em servi\u00e7os de sa\u00fade, \u00e9 vital separar e classificar aquelas informa\u00e7\u00f5es mais relevantes. Esta separa\u00e7\u00e3o permite uma segmenta\u00e7\u00e3o mais adequada, e consequentemente um atendimento personalizado, tal e qual um sistema apropriado de CRM.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As oportunidades nesse sentido s\u00e3o muitas. Ao baixar ou utilizar um aplicativo espec\u00edfico de sa\u00fade, por exemplo, fornecemos informa\u00e7\u00f5es muito valiosas ao marketing. Tais dados, quando ponderados de acordo com as leis de prote\u00e7\u00e3o de dados, podem auxiliar na segmenta\u00e7\u00e3o de acordo com as necessidades de cada paciente.\u00a0<\/span><\/p>\n<p><strong>4.Intelig\u00eancia Artificial e Machine Learning<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1359 size-full\" src=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/5405689621774336.jpeg\" alt=\"\" width=\"690\" height=\"462\" srcset=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/5405689621774336.jpeg 690w, https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/5405689621774336-300x201.jpeg 300w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Apesar de ser tratada como a grande inova\u00e7\u00e3o da atualidade, a Intelig\u00eancia artificial e o machine learning j\u00e1 tem sido fortemente utilizado em v\u00e1rios setores como a sa\u00fade. No entanto, sua tend\u00eancia de crescimento nos pr\u00f3ximos anos continua a ser forte.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dentre os benef\u00edcios de se utilizar a intelig\u00eancia artificial, est\u00e1 a robotiza\u00e7\u00e3o e padroniza\u00e7\u00e3o nos atendimentos. Isso pode ser feito atrav\u00e9s de um sistema de CRM, como mencionado no item 1, e quando implementados permitem que os funcion\u00e1rios atendam os pacientes de forma humanizada e com sabedoria.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Segundo <\/span><a href=\"https:\/\/www.healthcareitnews.com\/author\/paul-cerrato\"><span style=\"font-weight: 400;\">Paul Cerrato<\/span><\/a><span style=\"font-weight: 400;\">, jornalista m\u00e9dico e pesquisador Norte Americano, outro grande benef\u00edcio da intelig\u00eancia artificial \u00e9 o suporte no diagn\u00f3stico. Essa possibilidade de utiliza\u00e7\u00e3o iria reduzir drasticamente o n\u00famero de diagn\u00f3sticos errados, o que consequentemente acaba estabelecendo condi\u00e7\u00f5es melhores para assertividade no tratamento.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa melhora em diagn\u00f3sticos baseados em IA, tamb\u00e9m foi confirmada em recente relat\u00f3rio de previs\u00f5es at\u00e9 2038 da <\/span><a href=\"https:\/\/su.org\/\"><span style=\"font-weight: 400;\">Singularity University<\/span><\/a><span style=\"font-weight: 400;\">. Esse mesmo documento evidencia ainda que em 2020 recomenda\u00e7\u00f5es terap\u00eauticas ser\u00e3o usadas em centros m\u00e9dicos Americanos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, Paul ainda afirma que h\u00e1 muito caminho a se percorrer at\u00e9 chegarmos a esse alto n\u00edvel de aplicabilidade da intelig\u00eancia artificial e machine learning. O que essa tecnologia, que j\u00e1 existe e \u00e9 utilizada nos EUA, nos mostra \u00e9 a grande gama de possibilidades que essas tecnologias nos trazem.<\/span><\/p>\n<p><strong>5.Telemedicina<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1360 size-full\" src=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/4702002179997696.png\" alt=\"\" width=\"711\" height=\"550\" srcset=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/4702002179997696.png 711w, https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/4702002179997696-300x232.png 300w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A <\/span><a href=\"https:\/\/medium.com\/nomad-health\/the-rise-of-telemedicine-implications-for-doctors-in-2018-d3342a523fc0\"><span style=\"font-weight: 400;\">telemedicina<\/span><\/a><span style=\"font-weight: 400;\"> j\u00e1 vem sendo largamente utilizada por algumas cl\u00ednicas de sa\u00fade e promete ser uma pr\u00e1tica ainda mais comum. O marketing em servi\u00e7os de sa\u00fade \u00e9 um grande aliado nessa atividade, pois facilita as rela\u00e7\u00f5es m\u00e9dico-paciente e traz qualidade no atendimento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa tend\u00eancia est\u00e1 bem adequada a sociedade atual, onde a tecnologia auxiliou na busca por praticidade e conveni\u00eancia, enquanto oferece novas oportunidades de servi\u00e7os, principalmente. Nesse sentido, a telemedicina traz a oportunidade de tratamentos \u00e0 dist\u00e2ncia, com acompanhamentos feitos de forma digital.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outro grande fator de import\u00e2ncia na telemedicina \u00e9 a facilidade em mobilidade, uma vez que pessoas idosas, gr\u00e1vidas ou qualquer outro indiv\u00edduo que possua quest\u00f5es impeditivas de acesso a espa\u00e7os f\u00edsicos, se privilegiam.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tal fato tamb\u00e9m est\u00e1 estreitamente relacionado com o item anterior sobre a utiliza\u00e7\u00e3o da intelig\u00eancia artificial no marketing de sa\u00fade. Isso ocorre porque com a telemedicina os m\u00e9dicos tamb\u00e9m podem detectar e corrigir sinais precoces de doen\u00e7as graves, por exemplo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, especialistas e estudiosos afirmam que para implementar a telemedicina com sucesso, \u00e9 preciso treinamento t\u00e9cnico e um alto investimento financeiro, o que deve ser bem ponderado.\u00a0<\/span><\/p>\n<p><strong>6.Assistentes Virtuais<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1361 size-full\" src=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/5961248204914688.jpeg\" alt=\"\" width=\"726\" height=\"481\" srcset=\"https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/5961248204914688.jpeg 726w, https:\/\/mgapress.com.br\/blog\/wp-content\/uploads\/2020\/03\/5961248204914688-300x199.jpeg 300w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Esta tend\u00eancia j\u00e1 \u00e9 uma realidade utilizada por muitas cl\u00ednicas e hospitais pelo pa\u00eds, mas ainda continua se apresentando como uma grande promessa para 2020. Isso nos traz a tona novamente a rela\u00e7\u00e3o m\u00e9dico-paciente, pois um sistema automatizado de intera\u00e7\u00e3o permite um foco maior nas rela\u00e7\u00f5es humanas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, as assistentes virtuais permitem um agendamento r\u00e1pido de consultas bem como escolha por atendimento personalizado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por outro lado, \u00e9 importante enfatizar que se voc\u00ea est\u00e1 pensando em colocar um assistente virtual em seu neg\u00f3cio, \u00e9 preciso cuidado para n\u00e3o automatizar demais e perder o lado humano da coisa.\u00a0<\/span><\/p>\n<p><strong>7.Tecnologia humanizada<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Depois de todas essas tend\u00eancias apresentadas acima, duas coisas ficam bem claras:<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">A import\u00e2ncia da tecnologia e da transforma\u00e7\u00e3o digital para o marketing em servi\u00e7os de sa\u00fade;<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">O foco cada vez mais necess\u00e1rio na rela\u00e7\u00e3o m\u00e9dico-paciente, t\u00e3o mal conduzida atualmente;<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">N\u00e3o obstante, \u00e9 interessante observar o papel daquilo que a tecnologia avan\u00e7ada n\u00e3o pode contribuir, as rela\u00e7\u00f5es humanas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m do mais, pode-se observar claramente como a transforma\u00e7\u00e3o digital tem um papel fundamental no marketing em servi\u00e7os de sa\u00fade, pois atrav\u00e9s de um sistema de CRM corretamente implementado, um bom uso do Big data e intelig\u00eancia artificial aliado a telemedicina e assistentes virtuais o setor de sa\u00fade estar\u00e1 com certeza em um caminho evolutivo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gostou das tend\u00eancias apresentadas nesse artigo? Ent\u00e3o <\/span><a href=\"https:\/\/mgapress.com.br\/#formulario-2\"><span style=\"font-weight: 400;\">entre em contato conosco<\/span><\/a><span style=\"font-weight: 400;\"> e saiba como podemos te ajudar na implementa\u00e7\u00e3o dessas boas pr\u00e1ticas!<\/span><\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f787-o1\" lang=\"pt-BR\" dir=\"ltr\" data-wpcf7-id=\"787\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/blog\/wp-json\/wp\/v2\/posts\/1358#wpcf7-f787-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rios de contato\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"787\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_BR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f787-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p>Entre em <a href=\"https:\/\/mgapress.com.br\/fale-conosco\/\" target=\"_blank\">contato<\/a> conosco e descubra o que podemos oferecer.\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Qual seu nome completo?\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Seu E-mail Corporativo:\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Telefone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"E o seu Telefone com DDD?\" value=\"\" type=\"tel\" name=\"Telefone\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"seguimento\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Segmento da Empresa:\" value=\"\" type=\"text\" name=\"seguimento\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENTRAR EM CONTATO\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><small> 7 minutos<\/small> A transforma\u00e7\u00e3o digital \u00e9 um tema que vem sendo falado com bastante frequ\u00eancia no mundo atual, atravessando diversos setores econ\u00f4micos, sendo um deles a sa\u00fade. O marketing em servi\u00e7os de sa\u00fade \u00e9 um enorme desafio devido a sua complexidade, concorr\u00eancia acirrada e especificidades.\u00a0 Para superar essa barreira, o marketing tradicional por si s\u00f3 j\u00e1 n\u00e3o \u00e9 a melhor alternativa, \u00e9 preciso \u201cchamar refor\u00e7os\u201d no marketing digital e suas ferramentas.\u00a0 Foi pensando nisso que a MGA Press desenvolveu uma lista com as 5 <a href=\"https:\/\/mgapress.com.br\/blog\/6-ferramentas-de-marketing-na-area-da-saude-em-2020\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":2,"featured_media":1362,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,41],"tags":[],"class_list":{"0":"entry","1":"post","2":"publish","3":"author-michel-acherboim","4":"post-1358","6":"format-standard","7":"has-post-thumbnail","8":"category-assessoria","9":"category-comunicacao"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/posts\/1358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1358"}],"version-history":[{"count":0,"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/posts\/1358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/media\/1362"}],"wp:attachment":[{"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mgapress.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}